{"id":520,"date":"2017-09-04T14:44:47","date_gmt":"2017-09-04T12:44:47","guid":{"rendered":"https:\/\/www.editorialgeu.com\/blog\/?p=520"},"modified":"2017-09-04T14:45:52","modified_gmt":"2017-09-04T12:45:52","slug":"cambian-nino-asperger-clase-por-peticion-madres","status":"publish","type":"post","link":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/","title":{"rendered":"Cambian de clase a un ni\u00f1o con Asperger tras la petici\u00f3n de un grupo de madres"},"content":{"rendered":"<p>Este fin de semana, una noticia que nos ha dejado tan perplejos como indignados ha inundado las redes sociales y hasta ha llegado a protagonizar los titulares de diferentes medios de comunicaci\u00f3n. Se trata de la alegr\u00eda con la que un grupo de madres de un colegio de Argentina celebran que \u00abpor fin\u00bb han cambiado de grupo-clase a uno de los compa\u00f1eros de clase de sus hijos, diagnosticado de S\u00edndrome de Asperger.<!--more--><\/p>\n<p>Seg\u00fan ha informado la t\u00eda del menor, las madres del centro decidieron dejar de llevar a sus hijos al centro hasta que no cambiaran al alumno de clase, y as\u00ed se lo trasladaron a la Direcci\u00f3n del centro. Finalmente, el centro escolar cedi\u00f3 y cambi\u00f3 al menor a otro grupo.<\/p>\n<p>Despu\u00e9s de esta determinaci\u00f3n por parte del centro, las madres mostraron su satisfacci\u00f3n con el resultado a trav\u00e9s del grupo que compart\u00edan en <em>Whatsapp<\/em>. Con expresiones como \u00abAl fin una buena noticia!!!!!!!!!!! Era hora q se hagan valer los derechos \u00ab, \u00abQue bueno para los chicos!! Que puedan trabajar y estar tranquilos\u00bb, \u00abUn alivio para los nuestros\u00bb o \u00abGracias a Dios\u00bb compart\u00edan su alegr\u00eda y vitoreaban la decisi\u00f3n.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-531 aligncenter\" src=\"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/Conversaci\u00f3n-de-Whatsapp.jpeg\" alt=\"\" width=\"656\" height=\"369\" srcset=\"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/Conversaci\u00f3n-de-Whatsapp.jpeg 656w, https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/Conversaci\u00f3n-de-Whatsapp-300x169.jpeg 300w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/p>\n<p>Frente a esta noticia, desde Editorial GEU no pod\u00edamos hacer o\u00eddos sordos. Desde aqu\u00ed rechazamos y condenamos cualquier tipo de discriminaci\u00f3n en el aula, en pro de la inclusi\u00f3n de todos y cada uno de los alumnos. Y desde aqu\u00ed queremos hacer nuestra peque\u00f1a reflexi\u00f3n.<\/p>\n<p>Lo que m\u00e1s comentarios ha suscitado -y sigue suscitando- es la alegr\u00eda desmedida del grupo de madres con la decisi\u00f3n del centro. Una actitud a nuestro modo de ver vergonzosa y despreciable. \u00bfQu\u00e9 ocurrir\u00eda si ese peque\u00f1o fuera su hijo, su sobrino&#8230;? \u00bfD\u00f3nde est\u00e1 la empat\u00eda? \u00bfQu\u00e9 les est\u00e1n ense\u00f1ando a sus hijos con esa actitud?<\/p>\n<p>Sabemos que todav\u00eda queda un largo camino por recorrer: de concienciaci\u00f3n, para la inclusi\u00f3n, para evitar situaciones completamente discriminatorias como \u00e9sta. Pero al margen de esto, lo que m\u00e1s nos preocupa es la actuaci\u00f3n del centro. \u00bfC\u00f3mo es posible que en pleno siglo XXI tengamos que ver este tipo de actuaciones por parte de una instituci\u00f3n educativa? \u00bfC\u00f3mo pueden haber tomado la decisi\u00f3n de discriminar a un alumno por tener S\u00edndrome de Asperger? \u00bfBajo qu\u00e9 argumentaci\u00f3n? \u00bfCon qu\u00e9 criterio? \u00bfC\u00f3mo han permitido y perpetrado la eliminaci\u00f3n del derecho de ese menor?<\/p>\n<p>Y, por \u00faltimo, \u00bfalguien ha pensado en el peque\u00f1o? Salvo un comentario que parece ser un intento de empat\u00eda (\u00abOjal\u00e1 sea lo mejor para ese nene [\u00b7\u00b7\u00b7]\u00bb) nadie (\u00a1nadie!) ha pensado en lo que le puede provocar al peque\u00f1o ese cambio, \u00bfc\u00f3mo le explican al peque\u00f1o el porqu\u00e9 de ese cambio? \u00a1Si ni siquiera los mayores lo entendemos!<\/p>\n<p>Como en todo, hemos intentado ver el lado positivo de toda situaci\u00f3n que se presente. Y en este caso, solo podemos quedarnos con la reacci\u00f3n de las personas al rechazar la decisi\u00f3n y criticar la actuaci\u00f3n del grupo de madres mediante -sobre todo- las redes sociales. Queda, por lo menos, un halo de esperanza para la inclusi\u00f3n, la tolerancia y la educaci\u00f3n.<\/p>\n<p>Y vosotros, \u00bfqu\u00e9 opin\u00e1is?<\/p>\n<h6>Fuente:\u00a0<a href=\"http:\/\/www.lavanguardia.com\/vida\/20170903\/431027397175\/madres-celebran-colegio-eche-nino-asperger.html\">Un grupo de madres celebra que el colegio cambie de clase a un ni\u00f1o con Asperger<\/a>, publicado el\u00a003\/09\/2017 en La Vanguardia.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana, una noticia que nos ha dejado tan perplejos como indignados ha inundado las redes sociales y hasta ha llegado a protagonizar los titulares de diferentes medios de comunicaci\u00f3n. Se trata de la alegr\u00eda con la que un grupo de madres de un colegio de Argentina celebran que \u00abpor fin\u00bb han cambiado [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambian de clase a un ni\u00f1o con Asperger porque las madres lo piden<\/title>\n<meta name=\"description\" content=\"Nuestra reflexi\u00f3n acerca de la decisi\u00f3n de un centro escolar en Argentina de cambiar de clase a un alumno con Asperger tras la presi\u00f3n de las madres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambian de clase a un ni\u00f1o con Asperger porque las madres lo piden\" \/>\n<meta property=\"og:description\" content=\"Nuestra reflexi\u00f3n acerca de la decisi\u00f3n de un centro escolar en Argentina de cambiar de clase a un alumno con Asperger tras la presi\u00f3n de las madres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Editorial GEU\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-04T12:44:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-04T12:45:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/asperger.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"593\" \/>\n\t<meta property=\"og:image:height\" content=\"306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Zaida S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zaida S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/\"},\"author\":{\"name\":\"Zaida S\u00e1nchez\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#\\\/schema\\\/person\\\/1dca72a31573063b910f2d3919a34d9d\"},\"headline\":\"Cambian de clase a un ni\u00f1o con Asperger tras la petici\u00f3n de un grupo de madres\",\"datePublished\":\"2017-09-04T12:44:47+00:00\",\"dateModified\":\"2017-09-04T12:45:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/asperger.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/\",\"name\":\"Cambian de clase a un ni\u00f1o con Asperger porque las madres lo piden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/asperger.jpg\",\"datePublished\":\"2017-09-04T12:44:47+00:00\",\"dateModified\":\"2017-09-04T12:45:52+00:00\",\"description\":\"Nuestra reflexi\u00f3n acerca de la decisi\u00f3n de un centro escolar en Argentina de cambiar de clase a un alumno con Asperger tras la presi\u00f3n de las madres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/asperger.jpg\",\"contentUrl\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/asperger.jpg\",\"width\":593,\"height\":306,\"caption\":\"S\u00edndrome de Asperger\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/cambian-nino-asperger-clase-por-peticion-madres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambian de clase a un ni\u00f1o con Asperger tras la petici\u00f3n de un grupo de madres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/\",\"name\":\"Blog Editorial GEU\",\"description\":\"Actualidad, noticias y consejos por una Escuela Inclusiva\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#organization\",\"name\":\"Blog Editorial GEU\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/LogoGEU_Blog.png\",\"contentUrl\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/LogoGEU_Blog.png\",\"width\":1181,\"height\":477,\"caption\":\"Blog Editorial GEU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/#\\\/schema\\\/person\\\/1dca72a31573063b910f2d3919a34d9d\",\"name\":\"Zaida S\u00e1nchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/foto-perfil-skype-150x150.jpg\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/foto-perfil-skype-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/foto-perfil-skype-150x150.jpg\",\"caption\":\"Zaida S\u00e1nchez\"},\"description\":\"Periodista. Responsable de Comunicaci\u00f3n de Editorial GEU.\",\"url\":\"https:\\\/\\\/www.editorialgeu.com\\\/blog\\\/author\\\/zaida-sanchez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambian de clase a un ni\u00f1o con Asperger porque las madres lo piden","description":"Nuestra reflexi\u00f3n acerca de la decisi\u00f3n de un centro escolar en Argentina de cambiar de clase a un alumno con Asperger tras la presi\u00f3n de las madres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/","og_locale":"es_ES","og_type":"article","og_title":"Cambian de clase a un ni\u00f1o con Asperger porque las madres lo piden","og_description":"Nuestra reflexi\u00f3n acerca de la decisi\u00f3n de un centro escolar en Argentina de cambiar de clase a un alumno con Asperger tras la presi\u00f3n de las madres.","og_url":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/","og_site_name":"Blog Editorial GEU","article_published_time":"2017-09-04T12:44:47+00:00","article_modified_time":"2017-09-04T12:45:52+00:00","og_image":[{"width":593,"height":306,"url":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/asperger.jpg","type":"image\/jpeg"}],"author":"Zaida S\u00e1nchez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Zaida S\u00e1nchez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#article","isPartOf":{"@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/"},"author":{"name":"Zaida S\u00e1nchez","@id":"https:\/\/www.editorialgeu.com\/blog\/#\/schema\/person\/1dca72a31573063b910f2d3919a34d9d"},"headline":"Cambian de clase a un ni\u00f1o con Asperger tras la petici\u00f3n de un grupo de madres","datePublished":"2017-09-04T12:44:47+00:00","dateModified":"2017-09-04T12:45:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/www.editorialgeu.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/asperger.jpg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/","url":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/","name":"Cambian de clase a un ni\u00f1o con Asperger porque las madres lo piden","isPartOf":{"@id":"https:\/\/www.editorialgeu.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#primaryimage"},"image":{"@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/asperger.jpg","datePublished":"2017-09-04T12:44:47+00:00","dateModified":"2017-09-04T12:45:52+00:00","description":"Nuestra reflexi\u00f3n acerca de la decisi\u00f3n de un centro escolar en Argentina de cambiar de clase a un alumno con Asperger tras la presi\u00f3n de las madres.","breadcrumb":{"@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#primaryimage","url":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/asperger.jpg","contentUrl":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/09\/asperger.jpg","width":593,"height":306,"caption":"S\u00edndrome de Asperger"},{"@type":"BreadcrumbList","@id":"https:\/\/www.editorialgeu.com\/blog\/cambian-nino-asperger-clase-por-peticion-madres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.editorialgeu.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cambian de clase a un ni\u00f1o con Asperger tras la petici\u00f3n de un grupo de madres"}]},{"@type":"WebSite","@id":"https:\/\/www.editorialgeu.com\/blog\/#website","url":"https:\/\/www.editorialgeu.com\/blog\/","name":"Blog Editorial GEU","description":"Actualidad, noticias y consejos por una Escuela Inclusiva","publisher":{"@id":"https:\/\/www.editorialgeu.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.editorialgeu.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.editorialgeu.com\/blog\/#organization","name":"Blog Editorial GEU","url":"https:\/\/www.editorialgeu.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.editorialgeu.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2019\/11\/LogoGEU_Blog.png","contentUrl":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2019\/11\/LogoGEU_Blog.png","width":1181,"height":477,"caption":"Blog Editorial GEU"},"image":{"@id":"https:\/\/www.editorialgeu.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.editorialgeu.com\/blog\/#\/schema\/person\/1dca72a31573063b910f2d3919a34d9d","name":"Zaida S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/07\/foto-perfil-skype-150x150.jpg","url":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/07\/foto-perfil-skype-150x150.jpg","contentUrl":"https:\/\/www.editorialgeu.com\/blog\/wp-content\/uploads\/2017\/07\/foto-perfil-skype-150x150.jpg","caption":"Zaida S\u00e1nchez"},"description":"Periodista. Responsable de Comunicaci\u00f3n de Editorial GEU.","url":"https:\/\/www.editorialgeu.com\/blog\/author\/zaida-sanchez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/posts\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":12,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/posts\/520\/revisions"}],"predecessor-version":[{"id":535,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/posts\/520\/revisions\/535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/media\/534"}],"wp:attachment":[{"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/media?parent=520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/categories?post=520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.editorialgeu.com\/blog\/wp-json\/wp\/v2\/tags?post=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}